{"id":1510,"date":"2021-08-04T10:34:14","date_gmt":"2021-08-04T08:34:14","guid":{"rendered":"https:\/\/www.galerie-gabelsberg.de\/kontakt\/"},"modified":"2021-09-07T16:17:05","modified_gmt":"2021-09-07T14:17:05","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.8.2&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#210b00&#8243; background_color_gradient_end=&#8221;rgba(33,25,21,0)&#8221; background_color_gradient_type=&#8221;radial&#8221; background_color_gradient_direction_radial=&#8221;top right&#8221; background_color_gradient_start_position=&#8221;10%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.galerie-gabelsberg.de\/wp-content\/uploads\/2021\/05\/stage.jpg&#8221; custom_padding=&#8221;80px|0|80px||true|false&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;27px|0px|27px|0px|false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.8.2&#8243; text_font=&#8221;Open Sans||||||||&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;|800||on|||||&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.4em&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;700px&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;44px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_line_height_tablet=&#8221;1.4em&#8221; header_line_height_phone=&#8221;1.4em&#8221; header_line_height_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h1>Contact<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Gallery Section&#8221; _builder_version=&#8221;4.8.2&#8243; background_color=&#8221;#ffffff&#8221; width=&#8221;100%&#8221; custom_padding=&#8221;||0px||false|false&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.8.2&#8243;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Our Locations&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%249%%&#8221; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.8.2&#8243; header_font=&#8221;Open Sans|700|||||||&#8221; header_font_size=&#8221;19px&#8221; header_line_height=&#8221;1.1em&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_line_height=&#8221;1.5em&#8221; background_color=&#8221;#ffae00&#8243; background_layout=&#8221;dark&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||20px|20px|false|false&#8221; animation_style=&#8221;slide&#8221; locked=&#8221;off&#8221;]<\/p>\n<p>Gabelsbergerstr. 19<br \/> 80333 M\u00fcnchen<\/p>\n<p>Rindermarkt 2<br \/> 80331 M\u00fcnchen<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Phone &#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%264%%&#8221; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.8.2&#8243; header_font=&#8221;Open Sans|700|||||||&#8221; header_font_size=&#8221;19px&#8221; header_line_height=&#8221;1.1em&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_line_height=&#8221;1.5em&#8221; background_color=&#8221;#ffae00&#8243; background_layout=&#8221;dark&#8221; height=&#8221;168px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||20px|20px|false|false&#8221; animation_style=&#8221;slide&#8221; locked=&#8221;off&#8221;]phone: +49 89 592 336<br \/>\nmobile: 0170 809 099 4<\/p>\n<p>&nbsp;[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Email&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%238%%&#8221; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.8.2&#8243; header_font=&#8221;Open Sans|700|||||||&#8221; header_font_size=&#8221;19px&#8221; header_line_height=&#8221;1.1em&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_line_height=&#8221;1.5em&#8221; background_color=&#8221;#ffae00&#8243; background_layout=&#8221;dark&#8221; height=&#8221;168px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||20px|20px|false|false&#8221; animation_style=&#8221;slide&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><span style=\"color: #ffffff;\"><a href=\"mailto:service@galerie-gabelsberg.de\" style=\"color: #ffffff;\">service@galerie-gabelsberg.de<\/a><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.8.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221;][et_pb_row _builder_version=&#8221;4.8.2&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.8.2&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.8.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Open Sans|700|||||||&#8221; header_3_font_size=&#8221;19px&#8221; header_3_line_height=&#8221;1.3em&#8221;]<\/p>\n<h3>Contact form<\/h3>\n<p>You are also welcome to contact us using the following form.<br \/>\nWe will then contact you as quickly as possible.[\/et_pb_text][et_pb_code _builder_version=&#8221;4.8.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|20px|30px|20px|false|false&#8221; border_width_all=&#8221;13px&#8221; border_color_all=&#8221;rgba(0,0,0,0.06)&#8221;]<div id=\"quform-d850fb\" class=\"quform quform-2 quform-support-page-caching quform-is-first-page\"><form id=\"quform-form-d850fb\" class=\"quform-form quform-form-2\" action=\"\/en\/wp-json\/wp\/v2\/pages\/1510#quform-d850fb\" method=\"post\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-options=\"{&quot;id&quot;:2,&quot;uniqueId&quot;:&quot;d850fb&quot;,&quot;theme&quot;:&quot;&quot;,&quot;ajax&quot;:true,&quot;logic&quot;:{&quot;logic&quot;:[],&quot;dependents&quot;:[],&quot;elementIds&quot;:[],&quot;dependentElementIds&quot;:[],&quot;animate&quot;:true},&quot;currentPageId&quot;:1,&quot;errorsIcon&quot;:&quot;&quot;,&quot;updateFancybox&quot;:true,&quot;hasPages&quot;:true,&quot;pages&quot;:[1,9],&quot;pageProgressType&quot;:&quot;numbers&quot;,&quot;tooltipsEnabled&quot;:true,&quot;tooltipClasses&quot;:&quot;qtip-quform-dark qtip-shadow&quot;,&quot;tooltipMy&quot;:&quot;left center&quot;,&quot;tooltipAt&quot;:&quot;right center&quot;,&quot;isRtl&quot;:false,&quot;scrollOffset&quot;:-50,&quot;scrollSpeed&quot;:800}\"><button class=\"quform-default-submit\" name=\"quform_submit\" type=\"submit\" value=\"submit\"><\/button><div class=\"quform-form-inner quform-form-inner-2\"><input type=\"hidden\" name=\"quform_form_id\" value=\"2\" \/><input type=\"hidden\" name=\"quform_form_uid\" value=\"d850fb\" \/><input type=\"hidden\" name=\"quform_count\" value=\"1\" \/><input type=\"hidden\" name=\"form_url\" value=\"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/pages\/1510\" \/><input type=\"hidden\" name=\"referring_url\" value=\"\" \/><input type=\"hidden\" name=\"post_id\" value=\"\" \/><input type=\"hidden\" name=\"post_title\" value=\"\" \/><input type=\"hidden\" name=\"quform_current_page_id\" value=\"1\" \/><input type=\"hidden\" name=\"quform_csrf_token\" value=\"QJ5uFZUP1tqxtBSxk48xiCLMm987WkQXtfwH3C5y\" \/><div class=\"quform-elements quform-elements-2 quform-cf quform-responsive-elements-phone-landscape\"><div class=\"quform-page-progress quform-page-progress-type-numbers\"><div class=\"quform-page-progress-bar\" style=\"width: 50%;\"><span class=\"quform-page-progress-text\">Page <span class=\"quform-page-progress-number\">1<\/span> of 2<\/span><\/div><\/div><div class=\"quform-element quform-element-page quform-page-1 quform-page-2_1 quform-cf quform-group-style-plain quform-first-page quform-current-page\"><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-select quform-element-2_6 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_6\"><label class=\"quform-label-text\" for=\"quform_2_6_d850fb\">I would like to<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-2_6\"><div class=\"quform-input quform-input-select quform-input-2_6 quform-cf\"><select id=\"quform_2_6_d850fb\" name=\"quform_2_6\" class=\"quform-field quform-field-select quform-field-2_6\"><option value=\"\" selected=\"selected\">Please choose<\/option><option value=\"buy a painting\">buy a painting<\/option><option value=\"sell a painting\">sell a painting<\/option><option value=\"a consultation\">a consultation<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-text quform-element-2_7 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_7\"><label class=\"quform-label-text\" for=\"quform_2_7_d850fb\"> I am interested in the artist's paintings<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_7\"><div class=\"quform-input quform-input-text quform-input-2_7 quform-cf\"><input type=\"text\" id=\"quform_2_7_d850fb\" name=\"quform_2_7\" class=\"quform-field quform-field-text quform-field-2_7\" \/><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-text quform-element-2_8 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_8\"><label class=\"quform-label-text\" for=\"quform_2_8_d850fb\">I would like to sell a painting (name of the artist and name of the painting)<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_8\"><div class=\"quform-input quform-input-text quform-input-2_8 quform-cf\"><input type=\"text\" id=\"quform_2_8_d850fb\" name=\"quform_2_8\" class=\"quform-field quform-field-text quform-field-2_8\" \/><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-textarea quform-element-2_23 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_23\"><label class=\"quform-label-text\" for=\"quform_2_23_d850fb\">Other concerns<\/label><\/div><div class=\"quform-inner quform-inner-textarea quform-inner-2_23\"><div class=\"quform-input quform-input-textarea quform-input-2_23 quform-cf\"><textarea id=\"quform_2_23_d850fb\" name=\"quform_2_23\" class=\"quform-field quform-field-textarea quform-field-2_23\"><\/textarea><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-2_2 quform-cf quform-button-style-theme\"><div class=\"quform-button-next quform-button-next-default quform-button-next-2_2\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">Forward<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-9 quform-page-2_9 quform-cf quform-group-style-plain quform-last-page\"><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-row quform-element-row-2_11 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-2_12\"><div class=\"quform-element quform-element-text quform-element-2_14 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_14\"><label class=\"quform-label-text\" for=\"quform_2_14_d850fb\">First name<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_14\"><div class=\"quform-input quform-input-text quform-input-2_14 quform-cf\"><input type=\"text\" id=\"quform_2_14_d850fb\" name=\"quform_2_14\" class=\"quform-field quform-field-text quform-field-2_14\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-2_13\"><div class=\"quform-element quform-element-text quform-element-2_15 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_15\"><label class=\"quform-label-text\" for=\"quform_2_15_d850fb\">Surname<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_15\"><div class=\"quform-input quform-input-text quform-input-2_15 quform-cf\"><input type=\"text\" id=\"quform_2_15_d850fb\" name=\"quform_2_15\" class=\"quform-field quform-field-text quform-field-2_15\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-row quform-element-row-2_16 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-2_17\"><div class=\"quform-element quform-element-text quform-element-2_19 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_19\"><label class=\"quform-label-text\" for=\"quform_2_19_d850fb\">phone<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_19\"><div class=\"quform-input quform-input-text quform-input-2_19 quform-cf\"><input type=\"text\" id=\"quform_2_19_d850fb\" name=\"quform_2_19\" class=\"quform-field quform-field-text quform-field-2_19\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-2_18\"><div class=\"quform-element quform-element-email quform-element-2_20 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_20\"><label class=\"quform-label-text\" for=\"quform_2_20_d850fb\">email<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-email quform-inner-2_20\"><div class=\"quform-input quform-input-email quform-input-2_20 quform-cf\"><input type=\"email\" id=\"quform_2_20_d850fb\" name=\"quform_2_20\" class=\"quform-field quform-field-email quform-field-2_20\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-checkbox quform-element-2_21 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_21\"><label class=\"quform-label-text\" id=\"quform_2_21_d850fb_label\">Data protection<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-checkbox quform-inner-2_21\"><div class=\"quform-input quform-input-checkbox quform-input-2_21 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\" role=\"group\" aria-labelledby=\"quform_2_21_d850fb_label\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_2_21[]\" id=\"quform_2_21_d850fb_1\" class=\"quform-field quform-field-checkbox quform-field-2_21 quform-field-2_21_1\" value=\"I have read the privacy policy of this website and I agree to it.\" \/><label for=\"quform_2_21_d850fb_1\" class=\"quform-option-label quform-option-label-2_21_1\"><span class=\"quform-option-text\">I have read the privacy policy of this website and I agree to it.<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-2_10 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-2_10\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">Back<\/span><\/button><\/div><div class=\"quform-button-submit quform-button-submit-default quform-button-submit-2_10\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-submit\" value=\"submit\"><span class=\"quform-button-text quform-button-submit-text\">Send<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element-tree\"><label for=\"quform_2_0_d850fb\">This field should be left blank<\/label><input type=\"text\" id=\"quform_2_0_d850fb\" name=\"quform_2_0\" class=\"quform-field quform-field-tree quform-field-2_0\" tabindex=\"-1\" autocomplete=\"off\" \/><\/div><\/div><\/div><\/div><\/div><\/form><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Contact Banner&#8221; _builder_version=&#8221;4.8.2&#8243; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221;][et_pb_row _builder_version=&#8221;4.8.2&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code _builder_version=&#8221;4.8.2&#8243; _module_preset=&#8221;default&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2662.1223616897223!2d11.569412115777517!3d48.146446179224206!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x479e75ee7347faef%3A0x6d010b3dce455e2d!2sGabelsbergerstra%C3%9Fe%2019%2C%2080333%20M%C3%BCnchen!5e0!3m2!1sde!2sde!4v1628066361168!5m2!1sde!2sde\" width=\"100%\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ContactGabelsbergerstr. 19 80333 M\u00fcnchen Rindermarkt 2 80331 M\u00fcnchenphone: +49 89 592 336 mobile: 0170 809 099 4 &nbsp;service@galerie-gabelsberg.deContact form You are also welcome to contact us using the following form. We will then contact you as quickly as possible.<div id=\"quform-97e76b\" class=\"quform quform-2 quform-support-page-caching quform-is-first-page\"><form id=\"quform-form-97e76b\" class=\"quform-form quform-form-2\" action=\"\/en\/wp-json\/wp\/v2\/pages\/1510#quform-97e76b\" method=\"post\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-options=\"{&quot;id&quot;:2,&quot;uniqueId&quot;:&quot;97e76b&quot;,&quot;theme&quot;:&quot;&quot;,&quot;ajax&quot;:true,&quot;logic&quot;:{&quot;logic&quot;:[],&quot;dependents&quot;:[],&quot;elementIds&quot;:[],&quot;dependentElementIds&quot;:[],&quot;animate&quot;:true},&quot;currentPageId&quot;:1,&quot;errorsIcon&quot;:&quot;&quot;,&quot;updateFancybox&quot;:true,&quot;hasPages&quot;:true,&quot;pages&quot;:[1,9],&quot;pageProgressType&quot;:&quot;numbers&quot;,&quot;tooltipsEnabled&quot;:true,&quot;tooltipClasses&quot;:&quot;qtip-quform-dark qtip-shadow&quot;,&quot;tooltipMy&quot;:&quot;left center&quot;,&quot;tooltipAt&quot;:&quot;right center&quot;,&quot;isRtl&quot;:false,&quot;scrollOffset&quot;:-50,&quot;scrollSpeed&quot;:800}\"><button class=\"quform-default-submit\" name=\"quform_submit\" type=\"submit\" value=\"submit\"><\/button><div class=\"quform-form-inner quform-form-inner-2\"><input type=\"hidden\" name=\"quform_form_id\" value=\"2\" \/><input type=\"hidden\" name=\"quform_form_uid\" value=\"97e76b\" \/><input type=\"hidden\" name=\"quform_count\" value=\"2\" \/><input type=\"hidden\" name=\"form_url\" value=\"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/pages\/1510\" \/><input type=\"hidden\" name=\"referring_url\" value=\"\" \/><input type=\"hidden\" name=\"post_id\" value=\"\" \/><input type=\"hidden\" name=\"post_title\" value=\"\" \/><input type=\"hidden\" name=\"quform_current_page_id\" value=\"1\" \/><input type=\"hidden\" name=\"quform_csrf_token\" value=\"QJ5uFZUP1tqxtBSxk48xiCLMm987WkQXtfwH3C5y\" \/><div class=\"quform-elements quform-elements-2 quform-cf quform-responsive-elements-phone-landscape\"><div class=\"quform-page-progress quform-page-progress-type-numbers\"><div class=\"quform-page-progress-bar\" style=\"width: 50%;\"><span class=\"quform-page-progress-text\">Page <span class=\"quform-page-progress-number\">1<\/span> of 2<\/span><\/div><\/div><div class=\"quform-element quform-element-page quform-page-1 quform-page-2_1 quform-cf quform-group-style-plain quform-first-page quform-current-page\"><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-select quform-element-2_6 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_6\"><label class=\"quform-label-text\" for=\"quform_2_6_97e76b\">I would like to<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-2_6\"><div class=\"quform-input quform-input-select quform-input-2_6 quform-cf\"><select id=\"quform_2_6_97e76b\" name=\"quform_2_6\" class=\"quform-field quform-field-select quform-field-2_6\"><option value=\"\" selected=\"selected\">Please choose<\/option><option value=\"buy a painting\">buy a painting<\/option><option value=\"sell a painting\">sell a painting<\/option><option value=\"a consultation\">a consultation<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-text quform-element-2_7 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_7\"><label class=\"quform-label-text\" for=\"quform_2_7_97e76b\"> I am interested in the artist's paintings<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_7\"><div class=\"quform-input quform-input-text quform-input-2_7 quform-cf\"><input type=\"text\" id=\"quform_2_7_97e76b\" name=\"quform_2_7\" class=\"quform-field quform-field-text quform-field-2_7\" \/><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-text quform-element-2_8 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_8\"><label class=\"quform-label-text\" for=\"quform_2_8_97e76b\">I would like to sell a painting (name of the artist and name of the painting)<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_8\"><div class=\"quform-input quform-input-text quform-input-2_8 quform-cf\"><input type=\"text\" id=\"quform_2_8_97e76b\" name=\"quform_2_8\" class=\"quform-field quform-field-text quform-field-2_8\" \/><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-textarea quform-element-2_23 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_23\"><label class=\"quform-label-text\" for=\"quform_2_23_97e76b\">Other concerns<\/label><\/div><div class=\"quform-inner quform-inner-textarea quform-inner-2_23\"><div class=\"quform-input quform-input-textarea quform-input-2_23 quform-cf\"><textarea id=\"quform_2_23_97e76b\" name=\"quform_2_23\" class=\"quform-field quform-field-textarea quform-field-2_23\"><\/textarea><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-2_2 quform-cf quform-button-style-theme\"><div class=\"quform-button-next quform-button-next-default quform-button-next-2_2\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">Forward<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-9 quform-page-2_9 quform-cf quform-group-style-plain quform-last-page\"><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-row quform-element-row-2_11 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-2_12\"><div class=\"quform-element quform-element-text quform-element-2_14 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_14\"><label class=\"quform-label-text\" for=\"quform_2_14_97e76b\">First name<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_14\"><div class=\"quform-input quform-input-text quform-input-2_14 quform-cf\"><input type=\"text\" id=\"quform_2_14_97e76b\" name=\"quform_2_14\" class=\"quform-field quform-field-text quform-field-2_14\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-2_13\"><div class=\"quform-element quform-element-text quform-element-2_15 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_15\"><label class=\"quform-label-text\" for=\"quform_2_15_97e76b\">Surname<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_15\"><div class=\"quform-input quform-input-text quform-input-2_15 quform-cf\"><input type=\"text\" id=\"quform_2_15_97e76b\" name=\"quform_2_15\" class=\"quform-field quform-field-text quform-field-2_15\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-row quform-element-row-2_16 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-2_17\"><div class=\"quform-element quform-element-text quform-element-2_19 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_19\"><label class=\"quform-label-text\" for=\"quform_2_19_97e76b\">phone<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-2_19\"><div class=\"quform-input quform-input-text quform-input-2_19 quform-cf\"><input type=\"text\" id=\"quform_2_19_97e76b\" name=\"quform_2_19\" class=\"quform-field quform-field-text quform-field-2_19\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-2_18\"><div class=\"quform-element quform-element-email quform-element-2_20 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_20\"><label class=\"quform-label-text\" for=\"quform_2_20_97e76b\">email<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-email quform-inner-2_20\"><div class=\"quform-input quform-input-email quform-input-2_20 quform-cf\"><input type=\"email\" id=\"quform_2_20_97e76b\" name=\"quform_2_20\" class=\"quform-field quform-field-email quform-field-2_20\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-checkbox quform-element-2_21 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-2_21\"><label class=\"quform-label-text\" id=\"quform_2_21_97e76b_label\">Data protection<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-checkbox quform-inner-2_21\"><div class=\"quform-input quform-input-checkbox quform-input-2_21 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\" role=\"group\" aria-labelledby=\"quform_2_21_97e76b_label\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_2_21[]\" id=\"quform_2_21_97e76b_1\" class=\"quform-field quform-field-checkbox quform-field-2_21 quform-field-2_21_1\" value=\"I have read the privacy policy of this website and I agree to it.\" \/><label for=\"quform_2_21_97e76b_1\" class=\"quform-option-label quform-option-label-2_21_1\"><span class=\"quform-option-text\">I have read the privacy policy of this website and I agree to it.<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-2_10 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-2_10\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">Back<\/span><\/button><\/div><div class=\"quform-button-submit quform-button-submit-default quform-button-submit-2_10\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-submit\" value=\"submit\"><span class=\"quform-button-text quform-button-submit-text\">Send<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element-tree\"><label for=\"quform_2_0_97e76b\">This field should be left blank<\/label><input type=\"text\" id=\"quform_2_0_97e76b\" name=\"quform_2_0\" class=\"quform-field quform-field-tree quform-field-2_0\" tabindex=\"-1\" autocomplete=\"off\" \/><\/div><\/div><\/div><\/div><\/div><\/form><\/div><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1510","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact. Galerie Gabelsberg, Gabelsbergerstr. 19, 80333 M\u00fcnchen<\/title>\n<meta name=\"description\" content=\"You are also welcome to contact us using the following form. We will then contact you as quickly as possible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact. Galerie Gabelsberg, Gabelsbergerstr. 19, 80333 M\u00fcnchen\" \/>\n<meta property=\"og:description\" content=\"You are also welcome to contact us using the following form. We will then contact you as quickly as possible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Galerie Gabelsberg in M\u00fcnchen\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-07T14:17:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/\",\"url\":\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/\",\"name\":\"Contact. Galerie Gabelsberg, Gabelsbergerstr. 19, 80333 M\u00fcnchen\",\"isPartOf\":{\"@id\":\"https:\/\/www.galerie-gabelsberg.de\/#website\"},\"datePublished\":\"2021-08-04T08:34:14+00:00\",\"dateModified\":\"2021-09-07T14:17:05+00:00\",\"description\":\"You are also welcome to contact us using the following form. We will then contact you as quickly as possible.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.galerie-gabelsberg.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.galerie-gabelsberg.de\/#website\",\"url\":\"https:\/\/www.galerie-gabelsberg.de\/\",\"name\":\"Galerie Gabelsberg in M\u00fcnchen\",\"description\":\"Meistergem\u00e4lde des 19. und 20. Jahrhunderts \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.galerie-gabelsberg.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact. Galerie Gabelsberg, Gabelsbergerstr. 19, 80333 M\u00fcnchen","description":"You are also welcome to contact us using the following form. We will then contact you as quickly as possible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact. Galerie Gabelsberg, Gabelsbergerstr. 19, 80333 M\u00fcnchen","og_description":"You are also welcome to contact us using the following form. We will then contact you as quickly as possible.","og_url":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/","og_site_name":"Galerie Gabelsberg in M\u00fcnchen","article_modified_time":"2021-09-07T14:17:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/","url":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/","name":"Contact. Galerie Gabelsberg, Gabelsbergerstr. 19, 80333 M\u00fcnchen","isPartOf":{"@id":"https:\/\/www.galerie-gabelsberg.de\/#website"},"datePublished":"2021-08-04T08:34:14+00:00","dateModified":"2021-09-07T14:17:05+00:00","description":"You are also welcome to contact us using the following form. We will then contact you as quickly as possible.","breadcrumb":{"@id":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galerie-gabelsberg.de\/en\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.galerie-gabelsberg.de\/en\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.galerie-gabelsberg.de\/en\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.galerie-gabelsberg.de\/#website","url":"https:\/\/www.galerie-gabelsberg.de\/","name":"Galerie Gabelsberg in M\u00fcnchen","description":"Meistergem\u00e4lde des 19. und 20. Jahrhunderts ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galerie-gabelsberg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/pages\/1510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/comments?post=1510"}],"version-history":[{"count":5,"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/pages\/1510\/revisions"}],"predecessor-version":[{"id":1655,"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/pages\/1510\/revisions\/1655"}],"wp:attachment":[{"href":"https:\/\/www.galerie-gabelsberg.de\/en\/wp-json\/wp\/v2\/media?parent=1510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}